{"id":21040,"count":1,"description":"","link":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/","name":"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30","slug":"%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 Archives &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)<\/title>\n<meta name=\"description\" content=\"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/\",\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/\",\"name\":\"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 Archives &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)\",\"isPartOf\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/#website\"},\"description\":\"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..\",\"breadcrumb\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/#website\",\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/\",\"name\":\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)\",\"description\":\"Thailand Company Database\",\"publisher\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2556\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\",\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"url\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"contentUrl\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"width\":561,\"height\":172,\"caption\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\"},\"logo\":{\"@id\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\"},\"description\":\"\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e41\u0e01\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 (\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29: company) \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1b\u0e31\u0e08\u0e40\u0e08\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 (legal person) \u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e47\u0e08\u0e30\u0e16\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\",\"sameAs\":[\"https:\/\/www.thailandbusinessdatabase.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 Archives &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","description":"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/","url":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/","name":"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 Archives &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","isPartOf":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/#website"},"description":"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..","breadcrumb":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/tag\/%e0%b8%81%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%b2%e0%b8%b0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/company.thailandbusinessdatabase.com\/2556\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e23\u0e30\u0e40\u0e17\u0e32\u0e30"}]},{"@type":"WebSite","@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/#website","url":"https:\/\/company.thailandbusinessdatabase.com\/2556\/","name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","description":"Thailand Company Database","publisher":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/company.thailandbusinessdatabase.com\/2556\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/company.thailandbusinessdatabase.com\/2556\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef","name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","url":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","contentUrl":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","width":561,"height":172,"caption":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17"},"logo":{"@id":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg"},"description":"\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e41\u0e01\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 (\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29: company) \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1b\u0e31\u0e08\u0e40\u0e08\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 (legal person) \u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e47\u0e08\u0e30\u0e16\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19","sameAs":["https:\/\/www.thailandbusinessdatabase.com"]}]}},"_links":{"self":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2556\/wp-json\/wp\/v2\/tags\/21040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2556\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2556\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2556\/wp-json\/wp\/v2\/posts?tags=21040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}