{"id":13224,"date":"2016-11-24T03:00:49","date_gmt":"2016-11-23T20:00:49","guid":{"rendered":"http:\/\/thbusinessdatabase\/business-thailand-13224\/"},"modified":"2016-11-24T03:00:49","modified_gmt":"2016-11-23T20:00:49","slug":"%e0%b8%9a%e0%b8%88-%e0%b8%a2%e0%b8%b9%e0%b8%99%e0%b8%99%e0%b8%b2%e0%b8%99-%e0%b9%84%e0%b8%ae%e0%b9%80%e0%b8%8a%e0%b8%87-%e0%b8%ad%e0%b8%b4%e0%b8%99%e0%b8%94%e0%b8%b1%e0%b8%aa%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a5%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b9%8a%e0%b8%9b-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b9%84%e0%b8%97%e0%b8%a2-%e0%b8%88%e0%b8%b3%e0%b8%81%e0%b8%b1%e0%b8%94","status":"publish","type":"post","link":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/","title":{"rendered":"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14"},"content":{"rendered":"<p><center><\/p>\n<div class='txt_name'>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/div>\n<div id='companyname'><span class='th_name'>\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/span><\/div>\n<hr class='new3'><\/center><\/p>\n<div class='divTableCell'><strong>\u0e40\u0e25\u0e02\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 :<\/strong>0105558043651<\/div>\n<div class='divTableCell'><strong>\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \/ \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23 \/ \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \/ \u0e1c\u0e39\u0e49\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d :<\/strong> &#8211;<\/div>\n<div class='divTableCell'><strong>\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e21\u0e37\u0e48\u0e2d :<\/strong> 10-03-58<\/div>\n<div class='divTableCell'><strong>\u0e17\u0e38\u0e19\u0e08\u0e14\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19 :<\/strong> 1,000,000<\/div>\n<div class='divTableCell'><strong>\u0e02\u0e19\u0e32\u0e14\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 :<\/strong> n\/a<\/div>\n<div class='divTableCell'><strong>\u0e04\u0e19\u0e07\u0e32\u0e19 :<\/strong> n\/a<\/div>\n<div class='divTableCell'><strong>\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 :<\/strong> \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/div>\n<div class='divTableCell'><strong>\u0e23\u0e2b\u0e31\u0e2a\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c :<\/strong> &#8211;<\/div>\n<div class='divTableCell'><strong>\u0e2a\u0e16\u0e32\u0e19\u0e20\u0e32\u0e1e\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23 :<\/strong> \u0e22\u0e31\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48<\/div>\n<div class='divTableCell'><strong>\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07 :<\/strong> 302\/14 \u0e16\u0e19\u0e19\u0e23\u0e31\u0e0a\u0e14\u0e32\u0e20\u0e34\u0e40\u0e29\u0e01  \u0e41\u0e02\u0e27\u0e07\u0e2a\u0e32\u0e21\u0e40\u0e2a\u0e19\u0e19\u0e2d\u0e01 \u0e40\u0e02\u0e15\u0e2b\u0e49\u0e27\u0e22\u0e02\u0e27\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 10310<\/div>\n<div class='divTableCell'><strong>\u0e42\u0e17\u0e23\u0e28\u0e31\u0e1e\u0e17\u0e4c :<\/strong> &#8211;<\/div>\n<div class='divTableCell'><strong>\u0e42\u0e17\u0e23\u0e2a\u0e32\u0e23 :<\/strong> &#8211;<\/div>\n<div class='divTableCell'><strong>\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c :<\/strong> &#8211;<\/div>\n<div id='map'><strong>\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e22\u0e31\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong><iframe src='https:\/\/maps.google.com\/maps?&amp;q=\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19+\u0e44\u0e2e\u0e40\u0e0a\u0e07+\u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b+(\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)+\u0e08\u0e33\u0e01\u0e31\u0e14&amp;output=embed' marginwidth='0' marginheight='0' scrolling='no' width='100%' height='450' frameborder='0'><\/iframe><\/div>\n<div class='divTableCell'><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \/ \u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \/ \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 : \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong><\/div>\n<div class='divTableImg'><img src='https:\/\/www.thailandbusinessdatabase.com\/product_brand_marketing.jpg' alt='\u0e22\u0e35\u0e48\u0e2b\u0e49\u0e2d \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14'><\/div>\n<hr class='new3'>\n<div class='divTableCell'><strong>\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19\u0e27\u0e48\u0e32\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong> \u0e2b\u0e23\u0e37\u0e2d \u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e15\u0e23\u0e07\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e1d\u0e48\u0e32\u0e22\u0e1a\u0e38\u0e04\u0e04\u0e25<\/div>\n<p>&#8211; \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23<\/p>\n<hr class='new3'>\n<div class='divTableCell'><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e19\u0e30\u0e19\u0e33 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14<\/strong><\/div>\n<div class='divTableCell'><strong>\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\/\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 :<\/strong> \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25 \u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23<\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e31\u0e1a\u0e08\u0e49\u0e32\u0e07\u0e17\u0e33\u0e02\u0e2d\u0e07 \u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":712,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[24,1028,9803,9802,1027],"class_list":["post-13224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-23","tag-24","tag-1028","tag-9803","tag-9802","tag-1027"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)<\/title>\n<meta name=\"description\" content=\"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/company.thailandbusinessdatabase.com\/2558\/\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-13224\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/\"},\"author\":{\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\"},\"headline\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\",\"datePublished\":\"2016-11-23T20:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\"},\"image\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg\",\"keywords\":[\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\",\"\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\",\"\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\",\"\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25\"],\"articleSection\":[\"\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/\",\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/\",\"name\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)\",\"isPartOf\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg\",\"datePublished\":\"2016-11-23T20:00:49+00:00\",\"description\":\"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..\",\"breadcrumb\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage\",\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg\",\"contentUrl\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#website\",\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/\",\"name\":\"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)\",\"description\":\"Thailand Company Database\",\"publisher\":{\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef\",\"name\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"url\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"contentUrl\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\",\"width\":561,\"height\":172,\"caption\":\"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\"},\"logo\":{\"@id\":\"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg\"},\"description\":\"\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e41\u0e01\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 (\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29: company) \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1b\u0e31\u0e08\u0e40\u0e08\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 (legal person) \u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e47\u0e08\u0e30\u0e16\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19\",\"sameAs\":[\"https:\/\/www.thailandbusinessdatabase.com\"],\"url\":\"https:\/\/company.thailandbusinessdatabase.com\/2558\/author\/tbdadmin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","description":"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/company.thailandbusinessdatabase.com\/2558\/\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-13224\/","twitter_misc":{"Written by":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#article","isPartOf":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/"},"author":{"name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef"},"headline":"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14","datePublished":"2016-11-23T20:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/"},"wordCount":12,"publisher":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef"},"image":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage"},"thumbnailUrl":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg","keywords":["\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","\u0e04\u0e13\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25","\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23","\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14","\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1a\u0e38\u0e04\u0e04\u0e25"],"articleSection":["\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/","url":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/","name":"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 &#187; \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","isPartOf":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#website"},"primaryImageOfPage":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage"},"image":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage"},"thumbnailUrl":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg","datePublished":"2016-11-23T20:00:49+00:00","description":"\u0e04\u0e25\u0e34\u0e4a\u0e01\u0e14\u0e39 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e02\u0e2d\u0e07 \u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e43\u0e19 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database) \u0e1e\u0e23\u0e31\u0e48\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 \u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2b\u0e32\u0e07\u0e32\u0e19 \u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e07\u0e32\u0e19 \u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d \u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48 \u0e42\u0e0b\u0e40\u0e0a\u0e35\u0e22\u0e25 \u0e2d\u0e35\u0e40\u0e21\u0e25\u0e25\u0e4c..","breadcrumb":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#primaryimage","url":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg","contentUrl":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-content\/uploads\/2021\/08\/thailand-business-database-231.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/%e0%b8%81%e0%b8%a3%e0%b8%b8%e0%b8%87%e0%b9%80%e0%b8%97%e0%b8%9e%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%99%e0%b8%84%e0%b8%a3-13224\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/company.thailandbusinessdatabase.com\/2558\/"},{"@type":"ListItem","position":2,"name":"\u0e1a\u0e08.\u0e22\u0e39\u0e19\u0e19\u0e32\u0e19 \u0e44\u0e2e\u0e40\u0e0a\u0e07 \u0e2d\u0e34\u0e19\u0e14\u0e31\u0e2a\u0e40\u0e15\u0e23\u0e35\u0e22\u0e25\u0e01\u0e23\u0e38\u0e4a\u0e1b (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#website","url":"https:\/\/company.thailandbusinessdatabase.com\/2558\/","name":"\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (Thailand Company Database)","description":"Thailand Company Database","publisher":{"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/company.thailandbusinessdatabase.com\/2558\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":["Person","Organization"],"@id":"https:\/\/company.thailandbusinessdatabase.com\/2558\/#\/schema\/person\/73f10958273c5eb1a2e5347c51a86cef","name":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","url":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","contentUrl":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg","width":561,"height":172,"caption":"\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17"},"logo":{"@id":"https:\/\/www.thailandbusinessdatabase.com\/wp-content\/uploads\/2021\/05\/TBD-logo-white.jpg"},"description":"\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e19\u0e31\u0e49\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e43\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e19\u0e19\u0e34\u0e22\u0e21 \u0e0b\u0e36\u0e48\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e2a\u0e48\u0e27\u0e19\u0e21\u0e32\u0e01\u0e21\u0e35\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e01\u0e33\u0e44\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e07\u0e04\u0e31\u0e48\u0e07\u0e41\u0e01\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 (\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29: company) \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e0a\u0e19\u0e34\u0e14\u0e2b\u0e19\u0e36\u0e48\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e27\u0e1a\u0e23\u0e27\u0e21\u0e1b\u0e31\u0e08\u0e40\u0e08\u0e01\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e41\u0e25\u0e30\/\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2d\u0e37\u0e48\u0e19 \u0e1c\u0e39\u0e49\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e38\u0e49\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e25\u0e07\u0e17\u0e38\u0e19\u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e1a\u0e38\u0e04\u0e04\u0e25\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e38\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e38\u0e14\u0e2a\u0e19\u0e43\u0e08\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e08\u0e38\u0e14\u0e21\u0e38\u0e48\u0e07\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e2a\u0e27\u0e07\u0e2b\u0e32\u0e1c\u0e25\u0e01\u0e33\u0e44\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e27\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e0a\u0e48\u0e19\u0e19\u0e35\u0e49\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e01\u0e23\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e41\u0e25\u0e30\u0e15\u0e31\u0e27\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e40\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e01\u0e47\u0e08\u0e30\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e34\u0e15\u0e34\u0e1a\u0e38\u0e04\u0e04\u0e25 (legal person) \u0e0a\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e01\u0e47\u0e08\u0e30\u0e16\u0e39\u0e01\u0e15\u0e31\u0e49\u0e07\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e0a\u0e49\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e41\u0e17\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19","sameAs":["https:\/\/www.thailandbusinessdatabase.com"],"url":"https:\/\/company.thailandbusinessdatabase.com\/2558\/author\/tbdadmin\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/posts\/13224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/comments?post=13224"}],"version-history":[{"count":0,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/posts\/13224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/media\/712"}],"wp:attachment":[{"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/media?parent=13224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/categories?post=13224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/company.thailandbusinessdatabase.com\/2558\/wp-json\/wp\/v2\/tags?post=13224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}